{"id":8777,"date":"2024-07-24T11:24:26","date_gmt":"2024-07-24T10:24:26","guid":{"rendered":"https:\/\/aovepenaluna.com\/?p=8777"},"modified":"2024-07-29T11:46:05","modified_gmt":"2024-07-29T10:46:05","slug":"almazara-ecologica-portatil","status":"publish","type":"post","link":"https:\/\/aovepenaluna.com\/en\/almazara-ecologica-portatil\/","title":{"rendered":"Portable Organic Olive Oil Mill"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb||6px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp\u00bb alt=\u00bbAOVE Pe\u00f1a Luna &#8211; Almazara Ecol\u00f3gica Portatil\u00bb title_text=\u00bbDJI_0003&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb3px||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb25px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb20px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>One of the characteristics that makes our olive oils unique is their freshness. Thanks to our Portable Organic Olive Oil Mill, we can extract the EVOO \u2018in situ\u2019 by taking the mill to where the olives are and not the other way round, as is conventionally done. This production model is a great effort for us but it brings great advantages.<\/p>\n<p class=\"translation-block\"><strong>1- Oil quality:<\/strong> By taking the oil mill to the olive groves, we greatly reduce the time that passes from the time the olives are harvested until they are taken to the oil mill. At Pe\u00f1a Luna, it takes less than an hour from the time we pick the olives until the Extra Virgin Olive Oil is extracted.<\/p>\n<p class=\"translation-block\"><strong>2- Sustainability:<\/strong> Our family owns olive groves in different regions of Malaga, Seville and Extremadura. Moving all the olives to a central mill would involve a high energy cost and CO2 emissions. For this reason, by moving the mill we also reduce our energy costs and emissions.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_margin=\u00bb6px|||||\u00bb custom_padding=\u00bb3px||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: left;\"><span style=\"font-weight: 400;\">How is olive oil extracted?<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb2px||5px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb20px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>1- Cleaning and selection.<\/h3>\n<p>&nbsp;<\/p>\n<p>The first step when the olives arrive at the mill is to clean them of the remains of branches and leaves. To do this, sieves and pressurised air are used.<\/p>\n<p>Once the olives have been cleaned, our team removes the damaged olives that can impoverish the flavour of the oil.<\/p>\n<p>&nbsp;<\/p>\n<h3>2-Milling<\/h3>\n<p>The cleaned olives are placed in a hammer mill where they are crushed together with their pits to form a homogeneous paste. This step is crucial to release the oil contained in the cells of the olive pulp.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/WhatsApp-Image-2023-11-13-at-13.37.00-_1_.webp\u00bb alt=\u00bbAOVE Pe\u00f1a Luna &#8211; Equipo\u00bb title_text=\u00bbWhatsApp-Image-2023-11-13-at-13.37.00-_1_\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aovepenaluna.com\/wp-content\/uploads\/2024\/07\/IMG_3896-scaled.webp\u00bb alt=\u00bbAlmazara &#8211; Molino\u00bb title_text=\u00bbIMG_3896&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb0px||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb20px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>3- Milkshake<\/h3>\n<p>&nbsp;<\/p>\n<p>The paste obtained is subjected to a beating or kneading process at a controlled temperature (generally below 27\u00baC to obtain extra virgin oil). This process, which lasts between 20 and 40 minutes, allows the oil microdroplets to agglutinate, facilitating their subsequent extraction.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aovepenaluna.com\/wp-content\/uploads\/2024\/07\/IMG_3904-scaled.webp\u00bb alt=\u00bbAlmazara port\u00e1til &#8211; batidora\u00bb title_text=\u00bbIMG_3904&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb0px||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb20px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>4- Extraction<\/h3>\n<h4>Extraction Systems<\/h4>\n<p>There are different systems for separating the oil from the olive paste:<\/p>\n<p class=\"translation-block\"><strong>Traditional pressing:<\/strong> It uses hydraulic presses to compress the paste and extract the oil. This method is no longer used due to its lower efficiency and higher cost.<\/p>\n<p class=\"translation-block\"><strong>Continuous two-phase system:<\/strong> The pulp is centrifuged in a two-phase decanter that separates the oil and the alpech\u00edn (vegetation water and solids).<\/p>\n<p class=\"translation-block\"><strong>Continuous three-phase system:<\/strong> Similar to the previous one, but separates the oil, the alpech\u00edn and the solids separately.<\/p>\n<h4>Centrifugation<\/h4>\n<p>The oil obtained after the first extraction still contains water and impurities. To purify it, it is subjected to a second centrifugation that removes these impurities, resulting in a clean and clear oil.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aovepenaluna.com\/wp-content\/uploads\/2024\/07\/IMG_3908-scaled.webp\u00bb alt=\u00bbAlmazara portatil &#8211; decanter\u00bb title_text=\u00bbIMG_3908&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aovepenaluna.com\/wp-content\/uploads\/2024\/07\/IMG_3916-scaled.webp\u00bb alt=\u00bbAlmazara portatil &#8211; decanter\u00bb title_text=\u00bbIMG_3916&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb custom_padding=\u00bb0px||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb20px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><span style=\"font-weight: 400;\">5- Filtering.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Although some producers choose to market the oil unfiltered, most filter the oil to remove water and solid particles. This process ensures a more stable and better-presented final product.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">6- Storage<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">The purified oil is stored in stainless steel tanks or in inert packaging that protects the oil from light and oxygen, two factors that can deteriorate its quality. During storage, it is kept at a controlled temperature to preserve its organoleptic properties.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/tdJMNtSirAw\u00bb _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blog fullwidth=\u00bboff\u00bb posts_number=\u00bb3&#8243; include_categories=\u00bb71&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Una de las caracter\u00edsticas que hace \u00fanicos nuestros Aceites de Oliva es su frescura. Gracias a nuestra Almazara Ecol\u00f3gica Port\u00e1til, podemos extraer el AOVE \u201cin situ\u201d llevando la almazara donde est\u00e1 la aceituna y no al rev\u00e9s, como se hace de forma convencional. Este modelo de producci\u00f3n supone un gran esfuerzo para nosotros pero aporta [&hellip;]<\/p>","protected":false},"author":2,"featured_media":8047,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[78,71],"tags":[211,210],"class_list":["post-8777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura-regenerativa-blog","category-blog","tag-agricultura-regenerativa","tag-almazara"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Almazara Ecol\u00f3gica Port\u00e1til - Aceite de Oliva Virgen Extra Pe\u00f1a Luna<\/title>\n<meta name=\"description\" content=\"Descubre como elaboramos nuestro Aceite de Oliva Virgen Extra de manera sostenible gracias a nuestra Almazara Port\u00e1til que...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aovepenaluna.com\/en\/almazara-ecologica-portatil\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Almazara Ecol\u00f3gica Port\u00e1til - Aceite de Oliva Virgen Extra Pe\u00f1a Luna\" \/>\n<meta property=\"og:description\" content=\"Descubre como elaboramos nuestro Aceite de Oliva Virgen Extra de manera sostenible gracias a nuestra Almazara Port\u00e1til que...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aovepenaluna.com\/en\/almazara-ecologica-portatil\/\" \/>\n<meta property=\"og:site_name\" content=\"Aceite de Oliva Virgen Extra Pe\u00f1a Luna\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aovepenaluna\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T10:24:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T10:46:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Aove Pe\u00f1aluna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aove Pe\u00f1aluna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/\",\"url\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/\",\"name\":\"Almazara Ecol\u00f3gica Port\u00e1til - Aceite de Oliva Virgen Extra Pe\u00f1a Luna\",\"isPartOf\":{\"@id\":\"https:\/\/aovepenaluna.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp\",\"datePublished\":\"2024-07-24T10:24:26+00:00\",\"dateModified\":\"2024-07-29T10:46:05+00:00\",\"author\":{\"@id\":\"https:\/\/aovepenaluna.com\/#\/schema\/person\/7d1033d2544d6191bb163bcbbffd5268\"},\"description\":\"Descubre como elaboramos nuestro Aceite de Oliva Virgen Extra de manera sostenible gracias a nuestra Almazara Port\u00e1til que...\",\"breadcrumb\":{\"@id\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#primaryimage\",\"url\":\"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp\",\"contentUrl\":\"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp\",\"width\":2000,\"height\":1499,\"caption\":\"AOVE Pe\u00f1a Luna - Almazara Ecol\u00f3gica Portatil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/aovepenaluna.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Almazara Ecol\u00f3gica Port\u00e1til\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aovepenaluna.com\/#website\",\"url\":\"https:\/\/aovepenaluna.com\/\",\"name\":\"Aceite de Oliva Virgen Extra Pe\u00f1a Luna\",\"description\":\"Aceite de Oliva Virgen Extra Ecol\u00f3gico de m\u00e1xima calidad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aovepenaluna.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/aovepenaluna.com\/#\/schema\/person\/7d1033d2544d6191bb163bcbbffd5268\",\"name\":\"Aove Pe\u00f1aluna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/aovepenaluna.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/aovepenaluna.com\/wp-content\/litespeed\/avatar\/8485e5c02a5b523d665c2a9a7c20e75d.jpg?ver=1778149764\",\"contentUrl\":\"https:\/\/aovepenaluna.com\/wp-content\/litespeed\/avatar\/8485e5c02a5b523d665c2a9a7c20e75d.jpg?ver=1778149764\",\"caption\":\"Aove Pe\u00f1aluna\"},\"url\":\"https:\/\/aovepenaluna.com\/en\/author\/aovepe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Almazara Ecol\u00f3gica Port\u00e1til - Aceite de Oliva Virgen Extra Pe\u00f1a Luna","description":"Descubre como elaboramos nuestro Aceite de Oliva Virgen Extra de manera sostenible gracias a nuestra Almazara Port\u00e1til que...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aovepenaluna.com\/en\/almazara-ecologica-portatil\/","og_locale":"en_GB","og_type":"article","og_title":"Almazara Ecol\u00f3gica Port\u00e1til - Aceite de Oliva Virgen Extra Pe\u00f1a Luna","og_description":"Descubre como elaboramos nuestro Aceite de Oliva Virgen Extra de manera sostenible gracias a nuestra Almazara Port\u00e1til que...","og_url":"https:\/\/aovepenaluna.com\/en\/almazara-ecologica-portatil\/","og_site_name":"Aceite de Oliva Virgen Extra Pe\u00f1a Luna","article_publisher":"https:\/\/www.facebook.com\/aovepenaluna","article_published_time":"2024-07-24T10:24:26+00:00","article_modified_time":"2024-07-29T10:46:05+00:00","og_image":[{"width":2000,"height":1499,"url":"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp","type":"image\/webp"}],"author":"Aove Pe\u00f1aluna","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aove Pe\u00f1aluna","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/","url":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/","name":"Almazara Ecol\u00f3gica Port\u00e1til - Aceite de Oliva Virgen Extra Pe\u00f1a Luna","isPartOf":{"@id":"https:\/\/aovepenaluna.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#primaryimage"},"image":{"@id":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#primaryimage"},"thumbnailUrl":"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp","datePublished":"2024-07-24T10:24:26+00:00","dateModified":"2024-07-29T10:46:05+00:00","author":{"@id":"https:\/\/aovepenaluna.com\/#\/schema\/person\/7d1033d2544d6191bb163bcbbffd5268"},"description":"Descubre como elaboramos nuestro Aceite de Oliva Virgen Extra de manera sostenible gracias a nuestra Almazara Port\u00e1til que...","breadcrumb":{"@id":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#primaryimage","url":"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp","contentUrl":"https:\/\/aovepenaluna.com\/wp-content\/uploads\/2023\/11\/DJI_0003.webp","width":2000,"height":1499,"caption":"AOVE Pe\u00f1a Luna - Almazara Ecol\u00f3gica Portatil"},{"@type":"BreadcrumbList","@id":"https:\/\/aovepenaluna.com\/es\/almazara-ecologica-portatil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aovepenaluna.com\/es\/"},{"@type":"ListItem","position":2,"name":"Almazara Ecol\u00f3gica Port\u00e1til"}]},{"@type":"WebSite","@id":"https:\/\/aovepenaluna.com\/#website","url":"https:\/\/aovepenaluna.com\/","name":"Aceite de Oliva Virgen Extra Pe\u00f1a Luna","description":"Aceite de Oliva Virgen Extra Ecol\u00f3gico de m\u00e1xima calidad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aovepenaluna.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/aovepenaluna.com\/#\/schema\/person\/7d1033d2544d6191bb163bcbbffd5268","name":"Aove Pe\u00f1aluna","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/aovepenaluna.com\/#\/schema\/person\/image\/","url":"https:\/\/aovepenaluna.com\/wp-content\/litespeed\/avatar\/8485e5c02a5b523d665c2a9a7c20e75d.jpg?ver=1778149764","contentUrl":"https:\/\/aovepenaluna.com\/wp-content\/litespeed\/avatar\/8485e5c02a5b523d665c2a9a7c20e75d.jpg?ver=1778149764","caption":"Aove Pe\u00f1aluna"},"url":"https:\/\/aovepenaluna.com\/en\/author\/aovepe\/"}]}},"_links":{"self":[{"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/posts\/8777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/comments?post=8777"}],"version-history":[{"count":11,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/posts\/8777\/revisions"}],"predecessor-version":[{"id":8812,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/posts\/8777\/revisions\/8812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/media\/8047"}],"wp:attachment":[{"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/media?parent=8777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/categories?post=8777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aovepenaluna.com\/en\/wp-json\/wp\/v2\/tags?post=8777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}